{"id":19,"date":"2011-03-04T14:35:23","date_gmt":"2011-03-04T13:35:23","guid":{"rendered":"http:\/\/www.naturopathie-nord.fr\/blog\/?p=19"},"modified":"2025-12-04T09:09:49","modified_gmt":"2025-12-04T08:09:49","slug":"quelques-conseils-pour-rester-en-forme","status":"publish","type":"post","link":"https:\/\/www.naturopathie-nord.fr\/blog\/naturopathie\/quelques-conseils-pour-rester-en-forme","title":{"rendered":"Quelques conseils pour rester en forme"},"content":{"rendered":"<p>Si vous souhaitez rester en forme et en bonne sant\u00e9, commencez par appliquer ces quelques conseils :<\/p>\n<ul>\n<li><strong>Vie professionnelle<\/strong> : choisissez un m\u00e9tier qui vous plait. Il n&rsquo;y a rien de pire que de partir travailler tous les matins \u00e0 contre-coeur et d&rsquo;attendre que le week-end ou les vacances arrivent. Il vaut parfois mieux\u00a0 gagner moins mais \u00eatre \u00e9panoui dans sa vie professionnelle.<\/li>\n<li><strong>Faites vous plaisir<\/strong> : sortez en famille ou avec des amis, payez-vous de temps en temps un petit extra qui vous fera plaisir et vous d\u00e9tendra (un bon restaurant, un massage relaxant, un cin\u00e9ma, &#8230;).<\/li>\n<li><strong>Alimentation<\/strong> : mangez de fa\u00e7on \u00e9quilibr\u00e9e, de pr\u00e9f\u00e9rence des aliments bio, de saison et de r\u00e9gion. Privil\u00e9giez les l\u00e9gumes et les fruits frais, consommez les prot\u00e9ines animales avec mod\u00e9ration.<br \/>\nContrairement \u00e0 la m\u00e9decine classique, la naturopathie d\u00e9conseille la consommation des produits laitiers, particuli\u00e8rement ceux provenant du lait de la vache. Ceux-ci favoriseraient les allergies, le cancer, le diab\u00e8te, l&rsquo;ob\u00e9sit\u00e9 et\u00a0 l&rsquo;ost\u00e9oporose.<br \/>\n\u00c9vitez les aliments trop raffin\u00e9s comme les farines blanches et les sucres rapides. Si vous dig\u00e9rez mal, optez plut\u00f4t pour des c\u00e9r\u00e9ales semi-compl\u00e8tes.<br \/>\nPour sucrer vos pr\u00e9parations, prenez du sucre de canne complet (qui a gard\u00e9 toutes les vitamines et les oligo-\u00e9l\u00e9ments) ou de la st\u00e9via qui est un \u00e9dulcorant v\u00e9g\u00e9tal naturel.<br \/>\nNe consommez pas de produits all\u00e9g\u00e9s \u00e0 base d&rsquo;aspartame, ce dernier est consid\u00e9r\u00e9 comme toxique pour l&rsquo;organisme.<\/li>\n<li><strong>Mod\u00e9rez<\/strong> votre consommation de <strong>caf\u00e9<\/strong> et d&rsquo;<strong>alcool<\/strong>. Pr\u00e9f\u00e9rez le vin rouge au vin blanc et au vin ros\u00e9, limitez votre consommation \u00e0 un verre par jour pour accompagner le repas principal.<\/li>\n<li><strong>Bannir l&rsquo;utilisation du micro-ondes<\/strong> : en effet, ce moyen de cuisson moderne et rapide d\u00e9vitalise les aliments, modifie leur structure mol\u00e9culaire ainsi que leurs caract\u00e9ristiques physico-chimiques. Pr\u00e9f\u00e9rez la cuisson \u00e0 la vapeur qui pr\u00e9serve le mieux la qualit\u00e9 des aliments.<\/li>\n<li><strong>Prenez vos repas dans la bonne humeur<\/strong> : une alimentation saine mais prise dans de mauvaises conditions peut vous \u00eatre plus nocive qu&rsquo;un repas moyennement sain pris dans la joie et la bonne humeur avec des coll\u00e8gues ou des amis.<\/li>\n<li><strong>Buvez<\/strong> de l&rsquo;eau peu min\u00e9ralis\u00e9e, \u00e9vitez sodas et coca-cola qui sont n\u00e9fastes  pour l&rsquo;organisme et pourraient favoriser l&rsquo;ost\u00e9oporose. Le <strong>th\u00e9 vert<\/strong> a \u00e9galement de nombreuses vertus, mais soyez attentifs si vous avez une tendance \u00e0 l&rsquo;an\u00e9mie car le th\u00e9 est ch\u00e9lateur du fer.<\/li>\n<li><strong>Faites r\u00e9guli\u00e8rement de l&rsquo;exercice<\/strong> : de pr\u00e9f\u00e9rence le matin et dans la nature. Selon vos affinit\u00e9s et votre forme physique : marche, bicyclette, roller, natation, &#8230;<\/li>\n<li><strong>G\u00e9rez vos \u00e9motions<\/strong> : la gestion des \u00e9motions est primordiale dans la pr\u00e9servation de la sant\u00e9. Certaines pathologies ont une origine psycho-somatique et se d\u00e9clarent suite \u00e0 un choc \u00e9motionnel non g\u00e9r\u00e9.<\/li>\n<li><strong>Relaxez-vous<\/strong> : octroyez vous des instants de pause pour vous d\u00e9tendre, par exemple quand vous rentrez du travail ou le week-end. Plusieurs fois dans la journ\u00e9e, respirez profond\u00e9ment en utilisant la respiration ventrale. Certaines disciplines orientales comme le <strong>Qi Gong<\/strong>, le <strong>Tai-Chi<\/strong> ou le <strong>Yoga<\/strong> peuvent vous aider \u00e0 vous relaxer et \u00e0 chasser les tensions.<\/li>\n<li><strong>Dormez bien et suffisamment<\/strong> : un manque de sommeil ou un sommeil de mauvaise qualit\u00e9 finira par affaiblir votre organisme.<\/li>\n<li><strong>Respectez le rythme des saisons<\/strong> : l&rsquo;hiver est une saison propice au repos, soyez moins actif et sauf imp\u00e9ratif de sant\u00e9 n&rsquo;entamez ni r\u00e9gime, ni cure de d\u00e9toxination.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Si vous souhaitez rester en forme et en bonne sant\u00e9, commencez par appliquer ces quelques conseils : Vie professionnelle : choisissez un m\u00e9tier qui vous plait. Il n&rsquo;y a rien de pire que de partir travailler tous les matins \u00e0 contre-coeur et d&rsquo;attendre que le week-end ou les vacances arrivent. Il vaut parfois mieux\u00a0 gagner [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3],"tags":[14,13,10,8],"class_list":["post-19","post","type-post","status-publish","format-gallery","hentry","category-naturopathie","tag-alimentation","tag-forme","tag-hygiene-de-vie","tag-naturopathie-2","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/posts\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":14,"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/posts\/19\/revisions"}],"predecessor-version":[{"id":158,"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/posts\/19\/revisions\/158"}],"wp:attachment":[{"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/media?parent=19"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/categories?post=19"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naturopathie-nord.fr\/blog\/wp-json\/wp\/v2\/tags?post=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}